{"id":377,"count":9,"description":"","link":"https:\/\/matyodesign.hu\/de\/category\/termekek\/","name":"term\u00e9kek","slug":"termekek","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>term\u00e9kek Arch\u00edvum - matyodesign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/matyodesign.hu\/de\/category\/termekek\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"term\u00e9kek Arch\u00edvum - matyodesign\" \/>\n<meta property=\"og:url\" content=\"https:\/\/matyodesign.hu\/de\/category\/termekek\/\" \/>\n<meta property=\"og:site_name\" content=\"matyodesign\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/matyodesign.hu\\\/category\\\/termekek\\\/\",\"url\":\"https:\\\/\\\/matyodesign.hu\\\/category\\\/termekek\\\/\",\"name\":\"term\u00e9kek Arch\u00edvum - matyodesign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/matyodesign.hu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/matyodesign.hu\\\/category\\\/termekek\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/matyodesign.hu\\\/category\\\/termekek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/matyodesign.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"term\u00e9kek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/matyodesign.hu\\\/#website\",\"url\":\"https:\\\/\\\/matyodesign.hu\\\/\",\"name\":\"matyodesign\",\"description\":\"K\u00e9zzel. Szeretettel. Neked.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/matyodesign.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"term\u00e9kek Arch\u00edvum - matyodesign","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/matyodesign.hu\/de\/category\/termekek\/","og_locale":"de_DE","og_type":"article","og_title":"term\u00e9kek Arch\u00edvum - matyodesign","og_url":"https:\/\/matyodesign.hu\/de\/category\/termekek\/","og_site_name":"matyodesign","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/matyodesign.hu\/category\/termekek\/","url":"https:\/\/matyodesign.hu\/category\/termekek\/","name":"term\u00e9kek Arch\u00edvum - matyodesign","isPartOf":{"@id":"https:\/\/matyodesign.hu\/#website"},"breadcrumb":{"@id":"https:\/\/matyodesign.hu\/category\/termekek\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/matyodesign.hu\/category\/termekek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/matyodesign.hu\/"},{"@type":"ListItem","position":2,"name":"term\u00e9kek"}]},{"@type":"WebSite","@id":"https:\/\/matyodesign.hu\/#website","url":"https:\/\/matyodesign.hu\/","name":"matyodesign","description":"K\u00e9zzel. Szeretettel. Neked.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/matyodesign.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/matyodesign.hu\/de\/wp-json\/wp\/v2\/categories\/377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/matyodesign.hu\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/matyodesign.hu\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/matyodesign.hu\/de\/wp-json\/wp\/v2\/posts?categories=377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}